{"id":3248,"date":"2022-04-21T12:31:06","date_gmt":"2022-04-21T12:31:06","guid":{"rendered":"https:\/\/garbi.floatstudio.eu\/?page_id=3248"},"modified":"2022-04-21T12:31:06","modified_gmt":"2022-04-21T12:31:06","slug":"test-slider","status":"publish","type":"page","link":"https:\/\/garbi.floatstudio.eu\/en\/test-slider\/","title":{"rendered":"Test slider"},"content":{"rendered":"<p>[new_royalslider id=&#8221;5&#8243;]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>[new_royalslider id=&#8221;5&#8243;]<\/p>\n","protected":false},"author":62,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page_home.php","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"class_list":["post-3248","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/garbi.floatstudio.eu\/en\/wp-json\/wp\/v2\/pages\/3248","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/garbi.floatstudio.eu\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/garbi.floatstudio.eu\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/garbi.floatstudio.eu\/en\/wp-json\/wp\/v2\/users\/62"}],"replies":[{"embeddable":true,"href":"https:\/\/garbi.floatstudio.eu\/en\/wp-json\/wp\/v2\/comments?post=3248"}],"version-history":[{"count":0,"href":"https:\/\/garbi.floatstudio.eu\/en\/wp-json\/wp\/v2\/pages\/3248\/revisions"}],"wp:attachment":[{"href":"https:\/\/garbi.floatstudio.eu\/en\/wp-json\/wp\/v2\/media?parent=3248"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}