{"id":347,"date":"2017-03-11T19:27:41","date_gmt":"2017-03-11T19:27:41","guid":{"rendered":"https:\/\/garbi.floatstudio.eu\/cart\/"},"modified":"2017-05-29T08:29:10","modified_gmt":"2017-05-29T08:29:10","slug":"cart","status":"publish","type":"page","link":"https:\/\/garbi.floatstudio.eu\/en\/cart\/","title":{"rendered":"Pedido en curso"},"content":{"rendered":"\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"class_list":["post-347","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/garbi.floatstudio.eu\/en\/wp-json\/wp\/v2\/pages\/347","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/garbi.floatstudio.eu\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/garbi.floatstudio.eu\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/garbi.floatstudio.eu\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/garbi.floatstudio.eu\/en\/wp-json\/wp\/v2\/comments?post=347"}],"version-history":[{"count":0,"href":"https:\/\/garbi.floatstudio.eu\/en\/wp-json\/wp\/v2\/pages\/347\/revisions"}],"wp:attachment":[{"href":"https:\/\/garbi.floatstudio.eu\/en\/wp-json\/wp\/v2\/media?parent=347"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}